{"id":12817,"date":"2026-02-17T10:26:04","date_gmt":"2026-02-17T09:26:04","guid":{"rendered":"https:\/\/raschle-immobilien.ch\/immobilien\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\/"},"modified":"2026-05-13T08:50:16","modified_gmt":"2026-05-13T06:50:16","slug":"1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere","status":"publish","type":"casawp_property","link":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\/","title":{"rendered":"Charmantes Landhaus &#8211; Gepflegte Wohlf\u00fchloase mit sch\u00f6nem Garten und absoluter Privatsph\u00e4re"},"content":{"rendered":"<p>Das freistehende Einfamilienhaus mit s\u00fcdlicher Ausrichtung befindet sich an der M\u00f6slistrasse 10 in N\u00fcrensdorf, in einem ruhigen und kinderfreundlichen Wohnquartier. Diese gepflegte Immobilie im Landhausstil mit grossen Sprossenfenstern und Fensterl\u00e4den verw\u00f6hnen Sie mit viel Tageslicht in den Innenr\u00e4umen. Die Liegenschaft mit wundersch\u00f6nem Garten bietet viel Privatsph\u00e4re und ist perfekt f\u00fcr Familien oder Paare, die eine harmonische Umgebung mit hoher Lebensqualit\u00e4t sch\u00e4tzen. Die Ausn\u00fctzung ist nicht ausgesch\u00f6pft und l\u00e4sst eine Erweiterung zu.<\/p>\n<p><strong>Erdgeschoss<\/strong><br \/>Beim Eintreten empf\u00e4ngt Sie ein heller, offener Eingangsbereich mit Garderobe und einem erhebenden Blick in die Galerie im OG. Das Wohnzimmer mit bodentiefen Fenstern und mit Chemin\u00e9e betritt man durch einen Torbogen. Der angrenzende Essbereich bietet einen direkten Ausgang auf den gedeckten Gartensitzplatz mit grosser elektrischer Sonnenstore mit Steuerung. Hier verbringen Sie gesellige und entspannte Stunden im Freien, mit viel Privatsph\u00e4re und Aussicht in den sch\u00f6nen und gepflegten Garten. Die grossz\u00fcgige und helle K\u00fcche mit funktionaler Aufteilung verf\u00fcgt \u00fcber einen Fr\u00fchst\u00fcckstisch und zwei Zug\u00e4nge in den Ess- und Eingangsbereich. Im Nordostfl\u00fcgel befindet sich ein Zimmer mit Ausgang auf einen separaten Gartensitzplatz mit Sonnenstore. Hier geniessen Sie im Sommer angenehmen Schatten f\u00fcr eine kleine Auszeit. Dieser Raum eignet sich als B\u00fcro, G\u00e4stezimmer oder Studio. Erg\u00e4nzt wird das Raumangebot durch eine Nasszelle mit Dusche.<\/p>\n<p><strong>Obergeschoss<\/strong><br \/>Hier erwartet Sie ein grossz\u00fcgiges, lichtdurchflutetes Elternschlafzimmer mit Gaube und einem hochwertigen Einbauschrank mit raffiniertem Stauraumkonzept. Zwei weitere Zimmer bieten flexible Nutzungsm\u00f6glichkeiten &#8211; etwa als Kinder-, G\u00e4ste- oder Arbeitszimmer. In einem der Zimmer ist ein Schrank fest verbaut. Das Badezimmer ist mit Dusche, Badewanne und WC ausgestattet.\u00a0Edles Eichenparkett in allen Schlafzimmern und auf der Treppe sorgt f\u00fcr eine warme, behagliche Atmosph\u00e4re. Der Estrich bietet zus\u00e4tzlichen Stauraum.<\/p>\n<p><strong>Untergeschoss<br \/><\/strong>Der vielseitig nutzbare und beheizte Bastelraum verf\u00fcgt \u00fcber ein Fenster und \u00fcber eine Aussentreppe einen direkten Zugang in den Garten. Der grossz\u00fcgige Vorraum eignet sich ideal f\u00fcr eine Garderobe und die Aufbewahrung von Schuhen &#8211; jede Abstellfl\u00e4che ist somit optimal genutzt. Ein separater Trocknungsraum mit Secomat, ein Schutzraum, sowie ein Technikraum mit Waschmaschine, Lavabo, Wasserenth\u00e4rtungsanlage und Boiler bieten viel Stauraum und einen praktischen Mehrwert im Alltag. Der Keller ist mit einem Natursteinboden ausgestattet und eignet sich hervorragend als Weinkeller. Der ehemalige Tankraum fungiert heute als vielseitig nutzbarer Stauraum. Alle Decken sind weiss gestrichen, was zur gepflegten und hellen Gesamtwirkung beitr\u00e4gt.<\/p>\n<p><strong>Gartenanlage<\/strong><br \/>Der liebevoll angelegte Garten ist ein wahres Refugium f\u00fcr Naturliebhaber. Ob entspannte Stunden auf den Gartensitzpl\u00e4tzen oder Aktivit\u00e4ten im Gr\u00fcnen &#8211; ob in der Sonne oder im Schatten &#8211; hier findet jeder seinen Platz zum Abschalten und Geniessen. Dank der auserlesenen Bepflanzung bl\u00fcht das ganze Jahr \u00fcber eine bunte und abwechslungsreiche Flora und begeistern zu jeder Jahreszeit. Fr\u00fchjahrsblumen, sommerliche Stauden, aromatische Kr\u00e4uter, herbstliche Farbenpracht und Wintergr\u00fcnes erfreuen Herz und Seele. Ein Rasenroboter \u00fcbernimmt f\u00fcr Sie den Rasenschnitt. Durch die leichte Hanglage und das Nivellieren des Grundst\u00fccks ist ein Bord entstanden, das mit einer Gr\u00fcnhecke und Holzpalisaden uneingeschr\u00e4nkten Sichtschutz bietet und eine absolute Privatsph\u00e4re garantiert.<\/p>\n<p><strong>Garagen<\/strong><br \/>Die Garage bietet ausreichend Platz f\u00fcr zwei Fahrzeuge sowie zus\u00e4tzlichen Stauraum f\u00fcr Fahrr\u00e4der, Gartenger\u00e4te oder Werkzeuge. Ein separater Ausgang f\u00fchrt in den Garten auf der Ostseite. Auf dem grossen Einfahrtsbereich k\u00f6nnen zwei Autos hintereinander parkiert werden. Seitlich der Garage bietet ein offener Schopf Platz f\u00fcr Velos und Gartenwerkzeug.<\/p>\n<p>Erleben Sie den Charme dieser einzigartigen Immobilie bei einer pers\u00f6nlichen Besichtigung. Wir freuen uns auf Ihre Kontaktaufnahme!<\/p>\n<p>Besuchen Sie uns f\u00fcr weitere Informationen auf unserer Website unter www.raschle-immobilien.ch oder rufen Sie uns unter +41 44 888 77 70 an.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das freistehende Einfamilienhaus mit s\u00fcdlicher Ausrichtung befindet sich an der M\u00f6slistrasse 10 in N\u00fcrensdorf, in einem ruhigen und kinderfreundlichen Wohnquartier. Diese gepflegte Immobilie im Landhausstil mit grossen Sprossenfenstern und Fensterl\u00e4den verw\u00f6hnen Sie mit viel Tageslicht in den Innenr\u00e4umen. Die Liegenschaft mit wundersch\u00f6nem Garten bietet viel Privatsph\u00e4re und ist perfekt f\u00fcr Familien oder Paare, die eine [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":14942,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"casawp_category":[10,9],"casawp_feature":[],"casawp_utility":[11],"casawp_location":[14,24,15],"casawp_salestype":[12],"casawp_availability":[13],"casawp_region":[],"class_list":["post-12817","casawp_property","type-casawp_property","status-publish","has-post-thumbnail","hentry","casawp_category-house","casawp_category-single-house","casawp_utility-residential","casawp_location-country_ch","casawp_location-locality_nuerensdorf","casawp_location-region_zh","casawp_salestype-buy","casawp_availability-active"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Charmantes Landhaus - Gepflegte Wohlf\u00fchloase mit sch\u00f6nem Garten und absoluter Privatsph\u00e4re - Raschle Immobilien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Charmantes Landhaus - Gepflegte Wohlf\u00fchloase mit sch\u00f6nem Garten und absoluter Privatsph\u00e4re - Raschle Immobilien\" \/>\n<meta property=\"og:description\" content=\"Das freistehende Einfamilienhaus mit s\u00fcdlicher Ausrichtung befindet sich an der M\u00f6slistrasse 10 in N\u00fcrensdorf, in einem ruhigen und kinderfreundlichen Wohnquartier. Diese gepflegte Immobilie im Landhausstil mit grossen Sprossenfenstern und Fensterl\u00e4den verw\u00f6hnen Sie mit viel Tageslicht in den Innenr\u00e4umen. Die Liegenschaft mit wundersch\u00f6nem Garten bietet viel Privatsph\u00e4re und ist perfekt f\u00fcr Familien oder Paare, die eine [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\/\" \/>\n<meta property=\"og:site_name\" content=\"Raschle Immobilien\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T06:50:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\\\/\",\"url\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\\\/\",\"name\":\"Charmantes Landhaus - Gepflegte Wohlf\u00fchloase mit sch\u00f6nem Garten und absoluter Privatsph\u00e4re - Raschle Immobilien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-11664\\\/property-1711116\\\/766a13cadcc9529da760491e20c57c0e.jpeg?p=xl\",\"datePublished\":\"2026-02-17T09:26:04+00:00\",\"dateModified\":\"2026-05-13T06:50:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-11664\\\/property-1711116\\\/766a13cadcc9529da760491e20c57c0e.jpeg?p=xl\",\"contentUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-11664\\\/property-1711116\\\/766a13cadcc9529da760491e20c57c0e.jpeg?p=xl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immobilien\",\"item\":\"https:\\\/\\\/raschle-immobilien.ch\\\/immobilien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Charmantes Landhaus &#8211; Gepflegte Wohlf\u00fchloase mit sch\u00f6nem Garten und absoluter Privatsph\u00e4re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#website\",\"url\":\"https:\\\/\\\/raschle-immobilien.ch\\\/\",\"name\":\"Raschle Immobilien\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raschle-immobilien.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#organization\",\"name\":\"Raschle Immobilien\",\"url\":\"https:\\\/\\\/raschle-immobilien.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raschle-immobilien.ch\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2025\\\/11\\\/raschle-immobilien_logo.svg\",\"contentUrl\":\"https:\\\/\\\/raschle-immobilien.ch\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2025\\\/11\\\/raschle-immobilien_logo.svg\",\"width\":600,\"height\":204,\"caption\":\"Raschle Immobilien\"},\"image\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Charmantes Landhaus - Gepflegte Wohlf\u00fchloase mit sch\u00f6nem Garten und absoluter Privatsph\u00e4re - Raschle Immobilien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\/","og_locale":"en_US","og_type":"article","og_title":"Charmantes Landhaus - Gepflegte Wohlf\u00fchloase mit sch\u00f6nem Garten und absoluter Privatsph\u00e4re - Raschle Immobilien","og_description":"Das freistehende Einfamilienhaus mit s\u00fcdlicher Ausrichtung befindet sich an der M\u00f6slistrasse 10 in N\u00fcrensdorf, in einem ruhigen und kinderfreundlichen Wohnquartier. Diese gepflegte Immobilie im Landhausstil mit grossen Sprossenfenstern und Fensterl\u00e4den verw\u00f6hnen Sie mit viel Tageslicht in den Innenr\u00e4umen. Die Liegenschaft mit wundersch\u00f6nem Garten bietet viel Privatsph\u00e4re und ist perfekt f\u00fcr Familien oder Paare, die eine [&hellip;]","og_url":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\/","og_site_name":"Raschle Immobilien","article_modified_time":"2026-05-13T06:50:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\/","url":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\/","name":"Charmantes Landhaus - Gepflegte Wohlf\u00fchloase mit sch\u00f6nem Garten und absoluter Privatsph\u00e4re - Raschle Immobilien","isPartOf":{"@id":"https:\/\/raschle-immobilien.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\/#primaryimage"},"image":{"@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.casasoft.com\/media\/provider-11664\/property-1711116\/766a13cadcc9529da760491e20c57c0e.jpeg?p=xl","datePublished":"2026-02-17T09:26:04+00:00","dateModified":"2026-05-13T06:50:16+00:00","breadcrumb":{"@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raschle-immobilien.ch\/en\/immobilien\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\/#primaryimage","url":"https:\/\/cdn.casasoft.com\/media\/provider-11664\/property-1711116\/766a13cadcc9529da760491e20c57c0e.jpeg?p=xl","contentUrl":"https:\/\/cdn.casasoft.com\/media\/provider-11664\/property-1711116\/766a13cadcc9529da760491e20c57c0e.jpeg?p=xl"},{"@type":"BreadcrumbList","@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1711116en-charmantes-landhaus-gepflegte-wohlfuehloase-mit-schoenem-garten-und-absoluter-privatsphaere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/raschle-immobilien.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Immobilien","item":"https:\/\/raschle-immobilien.ch\/immobilien\/"},{"@type":"ListItem","position":3,"name":"Charmantes Landhaus &#8211; Gepflegte Wohlf\u00fchloase mit sch\u00f6nem Garten und absoluter Privatsph\u00e4re"}]},{"@type":"WebSite","@id":"https:\/\/raschle-immobilien.ch\/#website","url":"https:\/\/raschle-immobilien.ch\/","name":"Raschle Immobilien","description":"","publisher":{"@id":"https:\/\/raschle-immobilien.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raschle-immobilien.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/raschle-immobilien.ch\/#organization","name":"Raschle Immobilien","url":"https:\/\/raschle-immobilien.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/raschle-immobilien.ch\/#\/schema\/logo\/image\/","url":"https:\/\/raschle-immobilien.ch\/wp-content\/uploads\/sites\/17\/2025\/11\/raschle-immobilien_logo.svg","contentUrl":"https:\/\/raschle-immobilien.ch\/wp-content\/uploads\/sites\/17\/2025\/11\/raschle-immobilien_logo.svg","width":600,"height":204,"caption":"Raschle Immobilien"},"image":{"@id":"https:\/\/raschle-immobilien.ch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_property\/12817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_property"}],"about":[{"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/types\/casawp_property"}],"replies":[{"embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/comments?post=12817"}],"version-history":[{"count":0,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_property\/12817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/media\/14942"}],"wp:attachment":[{"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/media?parent=12817"}],"wp:term":[{"taxonomy":"casawp_category","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_category?post=12817"},{"taxonomy":"casawp_feature","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_feature?post=12817"},{"taxonomy":"casawp_utility","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_utility?post=12817"},{"taxonomy":"casawp_location","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_location?post=12817"},{"taxonomy":"casawp_salestype","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_salestype?post=12817"},{"taxonomy":"casawp_availability","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_availability?post=12817"},{"taxonomy":"casawp_region","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_region?post=12817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}