{"id":15001,"date":"2026-04-21T15:56:15","date_gmt":"2026-04-21T13:56:15","guid":{"rendered":"https:\/\/raschle-immobilien.ch\/immobilien\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\/"},"modified":"2026-07-15T08:25:51","modified_gmt":"2026-07-15T06:25:51","slug":"1737372en-neugierig-auf-den-wert-ihrer-immobilie","status":"publish","type":"casawp_property","link":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\/","title":{"rendered":"Neugierig auf den Wert Ihrer Immobilie?"},"content":{"rendered":"<h2>Raschle Immobilien sucht.<\/h2>\n<p>F\u00fcr unsere ausgew\u00e4hlte Kundschaft suchen wir laufend Einfamilienh\u00e4user und Mehrfamilienh\u00e4user.<\/p>\n<p>Ihre Immobilie k\u00f6nnte hervorragend zu den W\u00fcnschen unserer Interessenten passen.<br \/>Durch unser Netzwerk und den direkten Zugang zu K\u00e4ufern gestalten wir den Verkaufsprozess diskret, professionell und effizient.<\/p>\n<p>Wir freuen uns auf Ihre Kontaktaufnahme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erhalten Sie eine erste kostenlose Online-Schnellbewertung.<\/p>\n<p>Mit wenigen Klicks erhalten Sie eine erste unverbindliche Einsch\u00e4tzung &#8211; kostenlos und unkompliziert.<\/p>\n<p>Ihr Schl\u00fcssel zum Erfolg.<\/p>\n","protected":false},"author":0,"featured_media":15002,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"casawp_category":[10],"casawp_feature":[],"casawp_utility":[11],"casawp_location":[38,14,15],"casawp_salestype":[12],"casawp_availability":[13],"casawp_region":[],"class_list":["post-15001","casawp_property","type-casawp_property","status-publish","has-post-thumbnail","hentry","casawp_category-house","casawp_utility-residential","casawp_location-locality_bassersdorf","casawp_location-country_ch","casawp_location-region_zh","casawp_salestype-buy","casawp_availability-active"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neugierig auf den Wert Ihrer Immobilie? - Raschle Immobilien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neugierig auf den Wert Ihrer Immobilie? - Raschle Immobilien\" \/>\n<meta property=\"og:description\" content=\"Erhalten Sie eine erste kostenlose Online-Schnellbewertung. Mit wenigen Klicks erhalten Sie eine erste unverbindliche Einsch\u00e4tzung - kostenlos und unkompliziert. Ihr Schl\u00fcssel zum Erfolg.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\/\" \/>\n<meta property=\"og:site_name\" content=\"Raschle Immobilien\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T06:25:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\\\/\",\"url\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\\\/\",\"name\":\"Neugierig auf den Wert Ihrer Immobilie? - Raschle Immobilien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-11664\\\/property-1737372\\\/36ef7b466c127caebc712c7f6697cbed.jpeg?p=xl\",\"datePublished\":\"2026-04-21T13:56:15+00:00\",\"dateModified\":\"2026-07-15T06:25:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-11664\\\/property-1737372\\\/36ef7b466c127caebc712c7f6697cbed.jpeg?p=xl\",\"contentUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-11664\\\/property-1737372\\\/36ef7b466c127caebc712c7f6697cbed.jpeg?p=xl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immobilien\",\"item\":\"https:\\\/\\\/raschle-immobilien.ch\\\/immobilien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Neugierig auf den Wert Ihrer Immobilie?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#website\",\"url\":\"https:\\\/\\\/raschle-immobilien.ch\\\/\",\"name\":\"Raschle Immobilien\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raschle-immobilien.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#organization\",\"name\":\"Raschle Immobilien\",\"url\":\"https:\\\/\\\/raschle-immobilien.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raschle-immobilien.ch\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2025\\\/11\\\/raschle-immobilien_logo.svg\",\"contentUrl\":\"https:\\\/\\\/raschle-immobilien.ch\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2025\\\/11\\\/raschle-immobilien_logo.svg\",\"width\":600,\"height\":204,\"caption\":\"Raschle Immobilien\"},\"image\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neugierig auf den Wert Ihrer Immobilie? - Raschle Immobilien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\/","og_locale":"en_US","og_type":"article","og_title":"Neugierig auf den Wert Ihrer Immobilie? - Raschle Immobilien","og_description":"Erhalten Sie eine erste kostenlose Online-Schnellbewertung. Mit wenigen Klicks erhalten Sie eine erste unverbindliche Einsch\u00e4tzung - kostenlos und unkompliziert. Ihr Schl\u00fcssel zum Erfolg.","og_url":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\/","og_site_name":"Raschle Immobilien","article_modified_time":"2026-07-15T06:25:51+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\/","url":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\/","name":"Neugierig auf den Wert Ihrer Immobilie? - Raschle Immobilien","isPartOf":{"@id":"https:\/\/raschle-immobilien.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\/#primaryimage"},"image":{"@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.casasoft.com\/media\/provider-11664\/property-1737372\/36ef7b466c127caebc712c7f6697cbed.jpeg?p=xl","datePublished":"2026-04-21T13:56:15+00:00","dateModified":"2026-07-15T06:25:51+00:00","breadcrumb":{"@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raschle-immobilien.ch\/en\/immobilien\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\/#primaryimage","url":"https:\/\/cdn.casasoft.com\/media\/provider-11664\/property-1737372\/36ef7b466c127caebc712c7f6697cbed.jpeg?p=xl","contentUrl":"https:\/\/cdn.casasoft.com\/media\/provider-11664\/property-1737372\/36ef7b466c127caebc712c7f6697cbed.jpeg?p=xl"},{"@type":"BreadcrumbList","@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1737372en-neugierig-auf-den-wert-ihrer-immobilie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/raschle-immobilien.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Immobilien","item":"https:\/\/raschle-immobilien.ch\/immobilien\/"},{"@type":"ListItem","position":3,"name":"Neugierig auf den Wert Ihrer Immobilie?"}]},{"@type":"WebSite","@id":"https:\/\/raschle-immobilien.ch\/#website","url":"https:\/\/raschle-immobilien.ch\/","name":"Raschle Immobilien","description":"","publisher":{"@id":"https:\/\/raschle-immobilien.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raschle-immobilien.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/raschle-immobilien.ch\/#organization","name":"Raschle Immobilien","url":"https:\/\/raschle-immobilien.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/raschle-immobilien.ch\/#\/schema\/logo\/image\/","url":"https:\/\/raschle-immobilien.ch\/wp-content\/uploads\/sites\/17\/2025\/11\/raschle-immobilien_logo.svg","contentUrl":"https:\/\/raschle-immobilien.ch\/wp-content\/uploads\/sites\/17\/2025\/11\/raschle-immobilien_logo.svg","width":600,"height":204,"caption":"Raschle Immobilien"},"image":{"@id":"https:\/\/raschle-immobilien.ch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_property\/15001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_property"}],"about":[{"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/types\/casawp_property"}],"replies":[{"embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/comments?post=15001"}],"version-history":[{"count":1,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_property\/15001\/revisions"}],"predecessor-version":[{"id":15104,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_property\/15001\/revisions\/15104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/media\/15002"}],"wp:attachment":[{"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/media?parent=15001"}],"wp:term":[{"taxonomy":"casawp_category","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_category?post=15001"},{"taxonomy":"casawp_feature","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_feature?post=15001"},{"taxonomy":"casawp_utility","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_utility?post=15001"},{"taxonomy":"casawp_location","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_location?post=15001"},{"taxonomy":"casawp_salestype","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_salestype?post=15001"},{"taxonomy":"casawp_availability","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_availability?post=15001"},{"taxonomy":"casawp_region","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_region?post=15001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}