{"id":8275,"date":"2025-10-01T19:04:17","date_gmt":"2025-10-01T17:04:17","guid":{"rendered":"https:\/\/raschle-immobilien.ch\/immobilien\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\/"},"modified":"2026-05-13T08:36:42","modified_gmt":"2026-05-13T06:36:42","slug":"1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa","status":"publish","type":"casawp_property","link":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\/","title":{"rendered":"Freistehendes 8.5 Zimmer-Einfamilienhaus mit herrlicher Fern- und Seesicht in St\u00e4fa"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Charmantes Refugium mit massivem Erweiterungspotenzial<\/p>\n","protected":false},"author":1,"featured_media":8276,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"casawp_category":[10,9],"casawp_feature":[20,19,21],"casawp_utility":[11],"casawp_location":[14,23,15],"casawp_salestype":[12],"casawp_availability":[22],"casawp_region":[],"class_list":["post-8275","casawp_property","type-casawp_property","status-publish","has-post-thumbnail","hentry","casawp_category-house","casawp_category-single-house","casawp_feature-has-lake-view","casawp_feature-is-child-friendly","casawp_feature-is-sunny","casawp_utility-residential","casawp_location-country_ch","casawp_location-locality_staefa","casawp_location-region_zh","casawp_salestype-buy","casawp_availability-reference"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Freistehendes 8.5 Zimmer-Einfamilienhaus mit herrlicher Fern- und Seesicht in St\u00e4fa - Raschle Immobilien<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Freistehendes 8.5 Zimmer-Einfamilienhaus mit herrlicher Fern- und Seesicht in St\u00e4fa - Raschle Immobilien\" \/>\n<meta property=\"og:description\" content=\"Charmantes Refugium mit massivem Erweiterungspotenzial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\/\" \/>\n<meta property=\"og:site_name\" content=\"Raschle Immobilien\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T06:36:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\\\/\",\"url\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\\\/\",\"name\":\"Freistehendes 8.5 Zimmer-Einfamilienhaus mit herrlicher Fern- und Seesicht in St\u00e4fa - Raschle Immobilien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-11664\\\/property-1580706\\\/f7e26a0e3b91de57e7970b74e6bec64e.jpeg?p=xl\",\"datePublished\":\"2025-10-01T17:04:17+00:00\",\"dateModified\":\"2026-05-13T06:36:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-11664\\\/property-1580706\\\/f7e26a0e3b91de57e7970b74e6bec64e.jpeg?p=xl\",\"contentUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-11664\\\/property-1580706\\\/f7e26a0e3b91de57e7970b74e6bec64e.jpeg?p=xl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/immobilien\\\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/raschle-immobilien.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immobilien\",\"item\":\"https:\\\/\\\/raschle-immobilien.ch\\\/immobilien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Freistehendes 8.5 Zimmer-Einfamilienhaus mit herrlicher Fern- und Seesicht in St\u00e4fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#website\",\"url\":\"https:\\\/\\\/raschle-immobilien.ch\\\/\",\"name\":\"Raschle Immobilien\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/raschle-immobilien.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#organization\",\"name\":\"Raschle Immobilien\",\"url\":\"https:\\\/\\\/raschle-immobilien.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/raschle-immobilien.ch\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2025\\\/11\\\/raschle-immobilien_logo.svg\",\"contentUrl\":\"https:\\\/\\\/raschle-immobilien.ch\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2025\\\/11\\\/raschle-immobilien_logo.svg\",\"width\":600,\"height\":204,\"caption\":\"Raschle Immobilien\"},\"image\":{\"@id\":\"https:\\\/\\\/raschle-immobilien.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Freistehendes 8.5 Zimmer-Einfamilienhaus mit herrlicher Fern- und Seesicht in St\u00e4fa - Raschle Immobilien","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\/","og_locale":"en_US","og_type":"article","og_title":"Freistehendes 8.5 Zimmer-Einfamilienhaus mit herrlicher Fern- und Seesicht in St\u00e4fa - Raschle Immobilien","og_description":"Charmantes Refugium mit massivem Erweiterungspotenzial","og_url":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\/","og_site_name":"Raschle Immobilien","article_modified_time":"2026-05-13T06:36:42+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\/","url":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\/","name":"Freistehendes 8.5 Zimmer-Einfamilienhaus mit herrlicher Fern- und Seesicht in St\u00e4fa - Raschle Immobilien","isPartOf":{"@id":"https:\/\/raschle-immobilien.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\/#primaryimage"},"image":{"@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.casasoft.com\/media\/provider-11664\/property-1580706\/f7e26a0e3b91de57e7970b74e6bec64e.jpeg?p=xl","datePublished":"2025-10-01T17:04:17+00:00","dateModified":"2026-05-13T06:36:42+00:00","breadcrumb":{"@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/raschle-immobilien.ch\/en\/immobilien\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\/#primaryimage","url":"https:\/\/cdn.casasoft.com\/media\/provider-11664\/property-1580706\/f7e26a0e3b91de57e7970b74e6bec64e.jpeg?p=xl","contentUrl":"https:\/\/cdn.casasoft.com\/media\/provider-11664\/property-1580706\/f7e26a0e3b91de57e7970b74e6bec64e.jpeg?p=xl"},{"@type":"BreadcrumbList","@id":"https:\/\/raschle-immobilien.ch\/en\/immobilien\/1654521en-freistehendes-85-zimmer-einfamilienhaus-mit-herrlicher-fern-und-seesicht-in-staefa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/raschle-immobilien.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Immobilien","item":"https:\/\/raschle-immobilien.ch\/immobilien\/"},{"@type":"ListItem","position":3,"name":"Freistehendes 8.5 Zimmer-Einfamilienhaus mit herrlicher Fern- und Seesicht in St\u00e4fa"}]},{"@type":"WebSite","@id":"https:\/\/raschle-immobilien.ch\/#website","url":"https:\/\/raschle-immobilien.ch\/","name":"Raschle Immobilien","description":"","publisher":{"@id":"https:\/\/raschle-immobilien.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/raschle-immobilien.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/raschle-immobilien.ch\/#organization","name":"Raschle Immobilien","url":"https:\/\/raschle-immobilien.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/raschle-immobilien.ch\/#\/schema\/logo\/image\/","url":"https:\/\/raschle-immobilien.ch\/wp-content\/uploads\/sites\/17\/2025\/11\/raschle-immobilien_logo.svg","contentUrl":"https:\/\/raschle-immobilien.ch\/wp-content\/uploads\/sites\/17\/2025\/11\/raschle-immobilien_logo.svg","width":600,"height":204,"caption":"Raschle Immobilien"},"image":{"@id":"https:\/\/raschle-immobilien.ch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_property\/8275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_property"}],"about":[{"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/types\/casawp_property"}],"author":[{"embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/comments?post=8275"}],"version-history":[{"count":0,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_property\/8275\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/media\/8276"}],"wp:attachment":[{"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/media?parent=8275"}],"wp:term":[{"taxonomy":"casawp_category","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_category?post=8275"},{"taxonomy":"casawp_feature","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_feature?post=8275"},{"taxonomy":"casawp_utility","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_utility?post=8275"},{"taxonomy":"casawp_location","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_location?post=8275"},{"taxonomy":"casawp_salestype","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_salestype?post=8275"},{"taxonomy":"casawp_availability","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_availability?post=8275"},{"taxonomy":"casawp_region","embeddable":true,"href":"https:\/\/raschle-immobilien.ch\/en\/wp-json\/wp\/v2\/casawp_region?post=8275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}